﻿{"id":1048,"date":"2023-11-22T15:45:40","date_gmt":"2023-11-22T14:45:40","guid":{"rendered":"https:\/\/marcellevagba.com\/?p=1048"},"modified":"2024-01-30T18:13:51","modified_gmt":"2024-01-30T17:13:51","slug":"rejete-des-hommes-mais-aime-de-dieu","status":"publish","type":"post","link":"https:\/\/marcellevagba.com\/index.php\/2023\/11\/22\/rejete-des-hommes-mais-aime-de-dieu\/","title":{"rendered":"REJET\u00c9 DES HOMMES MAIS AIM\u00c9 DE DIEU"},"content":{"rendered":"\n<p>La pierre qu\u2019ont rejet\u00e9e ceux qui b\u00e2tissaient est devenue la principale de l\u2019angle. <strong>Psaumes 118v22<\/strong><br><\/p>\n\n\n\n<p>Plusieurs personnes ont \u00e9t\u00e9 rejet\u00e9es par les hommes (avant toi). David a \u00e9t\u00e9 rejet\u00e9 par Saul, Joseph a \u00e9t\u00e9 rejet\u00e9 par ses fr\u00e8res, Job a \u00e9t\u00e9 rejet\u00e9 par ses amis et m\u00eame le Seigneur J\u00e9sus a \u00e9t\u00e9 rejet\u00e9 par tout un peuple. Rejet\u00e9s des hommes, DIEU les a \u00e9lev\u00e9s au temps qu\u2019il a fix\u00e9. Ils ont \u00e9t\u00e9 rejet\u00e9s \u00e0 cause de leur \u00e9toile, \u00e0 cause de leur destin\u00e9e, \u00e0 cause de la gr\u00e2ce de Dieu sur eux. Ils ont connu la m\u00e9chancet\u00e9 des hommes et ont souffert. Mais ils n\u2019ont pas reni\u00e9 DIEU, ils n\u2019ont pas cess\u00e9 de croire en DIEU, d\u2019esp\u00e9rer<br>en DIEU.<\/p>\n\n\n\n<p>Si vous \u00eates rejet\u00e9 par vos parents, vos fr\u00e8res, vos amis, vos coll\u00e8gues, vos responsables, m\u00eame votre pasteur sachez que DIEU ne vous rejette pas. DIEU ne vous rejette pas. Ne regardez plus \u00e0 la bouche des hommes, au jugement des hommes mais regardez \u00e0 DIEU. Ne consid\u00e9rez plus le rejet des autres. Consid\u00e9rez l\u2019Amour de DIEU, consid\u00e9rez les promesses de DIEU \u00e0 votre \u00e9gard, consid\u00e9rez ses b\u00e9n\u00e9dictions. Int\u00e9ressez-vous au plan de DIEU pour votre vie et vous ennemis seront confus.<br>Quelque que soit ce que vous avez fait, ou ce que vous faites DIEU ne vous d\u00e9teste pas. DIEU a envoy\u00e9 son fils J\u00e9sus mourir sur la terre pour vous. Il vous aime et vous aidera \u00e0 devenir la personne qu\u2019il d\u00e9sire. M\u00eame si la terre enti\u00e8re, votre pays, votre quartier, votre \u00e9glise vous hait, vous rejette, vous juge, vous calomnie, vous critique, DIEU vous tend ses bras d\u2019amour. DIEU ne vous rejette pas. DIEU ne fait pas comme les autres. DIEU est DIEU. DIEU est bon et non m\u00e9chant. DIEU est plein de bont\u00e9 pour vous. Il est plein de compassion pour vous et vous manifestera son amour. DIEU veut votre joie. DIEU veut votre victoire, votre salut, votre gu\u00e9rison. Il vous faut donc fixer les yeux sur DIEU de peur d\u2019\u00eatre affaibli par l\u2019attitude des autres. Ne vous appuyez pas sur les autres, ne comptez pas sur les autres. Fixez vos yeux sur DIEU seul, car lui ne vous d\u00e9cevra jamais. DIEU est un DIEU juste. Il vous conna\u00eet mieux que les autres qui vous jugent. Il sait tout et voit tout. <\/p>\n\n\n\n<p>Les autres essaieront de vous \u00e9loigner du plan de DIEU par leurs comportements, ne tombez pas dans le pi\u00e8ge. Ignorez les choses vaines et avancez avec DIEU. Qu\u2019on vous traite de tous les noms, de tous les maux, ne tenez pas compte. Laissez-les vous juger, laissez\u2013les perdre leur temps \u00e0 d\u00e9finir votre caract\u00e8re, vos d\u00e9fauts, vos faiblesses. Qu\u2019on vous accuse, qu\u2019on vous condamne, qu\u2019on vous crucifie, regardez \u00e0 DIEU comme le Seigneur J\u00e9sus. DIEU les confondra \u00e0 un moment. Ils seront jug\u00e9s du jugement dont ils vous ont jug\u00e9s (<strong>Matthieu 7v2<\/strong>). DIEU seul est juge. DIEU vous \u00e9l\u00e8vera comme il a pr\u00e9vu. Car avec lui \u00ab il y a un temps pour tout, un temps pour toute chose sous les cieux \u00bb <strong>Eccl\u00e9siaste 3v1<\/strong>.<\/p>\n\n\n\n<p><br>Un jour, il fera de vous la pierre principale de votre famille, de votre quartier, de votre r\u00e9gion, de votre pays, de votre \u00e9glise\u2026.et ceux qui vous rejetaient seront couverts de honte et de confusion.<br>DIEU a \u00e9lev\u00e9 David, DIEU a \u00e9lev\u00e9 Joseph, DIEU a r\u00e9tabli Job, DIEU a \u00e9lev\u00e9 le Seigneur J\u00e9sus, DIEU vous \u00e9l\u00e8vera aussi.<\/p>\n\n\n\n<p><br>Marcelle VAGBA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La pierre qu\u2019ont rejet\u00e9e ceux qui b\u00e2tissaient est devenue la principale de l\u2019angle. Psaumes 118v22 Plusieurs personnes ont \u00e9t\u00e9 rejet\u00e9es par les hommes (avant toi). David a \u00e9t\u00e9 rejet\u00e9 par Saul, Joseph a \u00e9t\u00e9 rejet\u00e9 par ses fr\u00e8res, Job a \u00e9t\u00e9 rejet\u00e9 par ses amis et m\u00eame le Seigneur J\u00e9sus a \u00e9t\u00e9 rejet\u00e9 par tout [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":709,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-1048","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/marcellevagba.com\/index.php\/wp-json\/wp\/v2\/posts\/1048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcellevagba.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marcellevagba.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marcellevagba.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/marcellevagba.com\/index.php\/wp-json\/wp\/v2\/comments?post=1048"}],"version-history":[{"count":1,"href":"https:\/\/marcellevagba.com\/index.php\/wp-json\/wp\/v2\/posts\/1048\/revisions"}],"predecessor-version":[{"id":1049,"href":"https:\/\/marcellevagba.com\/index.php\/wp-json\/wp\/v2\/posts\/1048\/revisions\/1049"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marcellevagba.com\/index.php\/wp-json\/wp\/v2\/media\/709"}],"wp:attachment":[{"href":"https:\/\/marcellevagba.com\/index.php\/wp-json\/wp\/v2\/media?parent=1048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marcellevagba.com\/index.php\/wp-json\/wp\/v2\/categories?post=1048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marcellevagba.com\/index.php\/wp-json\/wp\/v2\/tags?post=1048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}